{"id":40484,"date":"2020-05-18T02:35:58","date_gmt":"2020-05-18T00:35:58","guid":{"rendered":"https:\/\/seminarhotels-schweiz.com\/de\/?page_id=40484"},"modified":"2020-06-16T16:57:58","modified_gmt":"2020-06-16T14:57:58","slug":"veranstaltungen","status":"publish","type":"page","link":"https:\/\/winterthur-seminarhotels.ch\/en\/events\/","title":{"rendered":"Events"},"content":{"rendered":"<p>What else is going on in the region? Here you will find current events, trade fairs, sports and cultural events.<\/p>","protected":false},"excerpt":{"rendered":"<p>What else is going on in the region? Here you will find current events, trade fairs, sports and cultural events.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.3 (Yoast SEO v20.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Events in Ihrer Region | MICE Service Group | Seminar hotels in Winterthur<\/title>\n<meta name=\"description\" content=\"Veranstaltungen: Was ist sonst noch los in der Region? Hier finden Sie aktuelle Veranstaltungen, Messen, Sportveranstaltungen und kulturelle Events.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Events\" \/>\n<meta property=\"og:description\" content=\"Veranstaltungen: Was ist sonst noch los in der Region? Hier finden Sie aktuelle Veranstaltungen, Messen, Sportveranstaltungen und kulturelle Events.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-16T14:57:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/\",\"url\":\"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/\",\"name\":\"Events in Ihrer Region | MICE Service Group\",\"isPartOf\":{\"@id\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/#website\"},\"datePublished\":\"2020-05-18T00:35:58+00:00\",\"dateModified\":\"2020-06-16T14:57:58+00:00\",\"description\":\"Veranstaltungen: Was ist sonst noch los in der Region? Hier finden Sie aktuelle Veranstaltungen, Messen, Sportveranstaltungen und kulturelle Events.\",\"breadcrumb\":{\"@id\":\"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/#website\",\"url\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/\",\"name\":\"winterthur-seminarhotels.ch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/berneroberland-seminarhotels.ch\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Events in Ihrer Region | MICE Service Group | Seminar hotels in Winterthur","description":"Veranstaltungen: Was ist sonst noch los in der Region? Hier finden Sie aktuelle Veranstaltungen, Messen, Sportveranstaltungen und kulturelle Events.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/","og_locale":"en_US","og_type":"article","og_title":"Events","og_description":"Veranstaltungen: Was ist sonst noch los in der Region? Hier finden Sie aktuelle Veranstaltungen, Messen, Sportveranstaltungen und kulturelle Events.","og_url":"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/","article_modified_time":"2020-06-16T14:57:58+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/","url":"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/","name":"Events in Ihrer Region | MICE Service Group","isPartOf":{"@id":"https:\/\/berneroberland-seminarhotels.ch\/de\/#website"},"datePublished":"2020-05-18T00:35:58+00:00","dateModified":"2020-06-16T14:57:58+00:00","description":"Veranstaltungen: Was ist sonst noch los in der Region? Hier finden Sie aktuelle Veranstaltungen, Messen, Sportveranstaltungen und kulturelle Events.","breadcrumb":{"@id":"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/klagenfurt-tagungshotels.at\/de\/veranstaltungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/berneroberland-seminarhotels.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen"}]},{"@type":"WebSite","@id":"https:\/\/berneroberland-seminarhotels.ch\/de\/#website","url":"https:\/\/berneroberland-seminarhotels.ch\/de\/","name":"winterthur-seminarhotels.ch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berneroberland-seminarhotels.ch\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/winterthur-seminarhotels.ch\/en\/wp-json\/wp\/v2\/pages\/40484"}],"collection":[{"href":"https:\/\/winterthur-seminarhotels.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/winterthur-seminarhotels.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/winterthur-seminarhotels.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/winterthur-seminarhotels.ch\/en\/wp-json\/wp\/v2\/comments?post=40484"}],"version-history":[{"count":0,"href":"https:\/\/winterthur-seminarhotels.ch\/en\/wp-json\/wp\/v2\/pages\/40484\/revisions"}],"wp:attachment":[{"href":"https:\/\/winterthur-seminarhotels.ch\/en\/wp-json\/wp\/v2\/media?parent=40484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}